{"id":33814,"date":"2025-10-31T16:54:04","date_gmt":"2025-10-31T09:54:04","guid":{"rendered":"https:\/\/www.psu.ac.th\/trang\/?p=33814"},"modified":"2025-11-03T08:37:42","modified_gmt":"2025-11-03T01:37:42","slug":"%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%aa%e0%b8%87%e0%b8%82%e0%b8%a5-36","status":"publish","type":"post","link":"https:\/\/www.psu.ac.th\/trang\/archives\/33814","title":{"rendered":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e2d\u0e31\u0e15\u0e23\u0e32"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e2d\u0e31\u0e15\u0e23\u0e32\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e1a\u0e31\u0e14\u0e19\u0e35\u0e49 \u0e08\u0e19\u0e16\u0e36\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 28 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2568\u00a0 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e17\u0e32\u0e07\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u00a0 https:\/\/resume.psu.ac.th \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e14\u0e31\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e41\u0e19\u0e1a\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e19\u0e35\u0e49<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49-\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.\"><\/object><a id=\"wp-block-file--media-e09509bb-9407-498b-b185-46fc4e00efcb\" href=\"https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49-\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.pdf\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04<\/a><a href=\"https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49-\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-e09509bb-9407-498b-b185-46fc4e00efcb\">Download<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e2d\u0e31\u0e15\u0e23\u0e32\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e1a\u0e31\u0e14\u0e19\u0e35\u0e49 \u0e08\u0e19\u0e16\u0e36\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 28 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2568\u00a0 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e17\u0e32\u0e07\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u00a0 https:\/\/resume.psu.ac.th \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e14\u0e31\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e41\u0e19\u0e1a\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e19\u0e35\u0e49<\/p>\n","protected":false},"author":38,"featured_media":33819,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_front_end_style_editor":"no","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":"","_links_to":"","_links_to_target":""},"categories":[121,32,8],"tags":[],"class_list":["post-33814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category--th","category-32","category-8","entry","has-media"],"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e2d\u0e31\u0e15\u0e23\u0e32 - Prince of Songkla University, Trang Campus PSU Trang - \u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07<\/title>\n<meta name=\"description\" content=\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 (PSU Trang) \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e43\u0e19\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.psu.ac.th\/trang\/archives\/33814\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e2d\u0e31\u0e15\u0e23\u0e32 - Prince of Songkla University, Trang Campus PSU Trang - \u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07\" \/>\n<meta property=\"og:description\" content=\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 (PSU Trang) \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e43\u0e19\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.psu.ac.th\/trang\/archives\/33814\" \/>\n<meta property=\"og:site_name\" content=\"Prince of Songkla University, Trang Campus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/psutrangcampus5\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-31T09:54:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-03T01:37:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pronchita.s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@psutrangcampus\" \/>\n<meta name=\"twitter:site\" content=\"@psutrangcampus\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"pronchita.s\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/archives\\\/33814#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/archives\\\/33814\"},\"author\":{\"name\":\"pronchita.s\",\"@id\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/#\\\/schema\\\/person\\\/0482e4f1fb579d3e7720f8b7b22c8852\"},\"headline\":\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e2d\u0e31\u0e15\u0e23\u0e32\",\"datePublished\":\"2025-10-31T09:54:04+00:00\",\"dateModified\":\"2025-11-03T01:37:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/archives\\\/33814\"},\"wordCount\":6,\"publisher\":{\"@id\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/archives\\\/33814#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/wp-content\\\/uploads\\\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.jpg\",\"articleSection\":[\"\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\",\"\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\",\"\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e30\u0e19\u0e33\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/archives\\\/33814\",\"url\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/archives\\\/33814\",\"name\":\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e2d\u0e31\u0e15\u0e23\u0e32 - Prince of Songkla University, Trang Campus PSU Trang - \u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/archives\\\/33814#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/archives\\\/33814#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/wp-content\\\/uploads\\\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.jpg\",\"datePublished\":\"2025-10-31T09:54:04+00:00\",\"dateModified\":\"2025-11-03T01:37:42+00:00\",\"description\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 (PSU Trang) \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e43\u0e19\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/archives\\\/33814#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/archives\\\/33814\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/archives\\\/33814#primaryimage\",\"url\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/wp-content\\\/uploads\\\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.jpg\",\"contentUrl\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/wp-content\\\/uploads\\\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.jpg\",\"width\":940,\"height\":788},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/archives\\\/33814#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e2d\u0e31\u0e15\u0e23\u0e32\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/#website\",\"url\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/\",\"name\":\"Prince of Songkla University, Trang Campus\",\"description\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e25\u0e27\u0e31\u0e15 \u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e21\u0e38\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33 1 \u0e43\u0e19 5 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e17\u0e38\u0e01\u0e14\u0e49\u0e32\u0e19 \u0e2a\u0e21\u0e31\u0e04\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e41\u0e25\u0e49\u0e27\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/#organization\"},\"alternateName\":\"\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 - PSU Trang\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/#organization\",\"name\":\"Prince of Songkla University, Trang Campus\",\"alternateName\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07\",\"url\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/cropped-PSU_TRANG-TH-scaled-10.png\",\"contentUrl\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/cropped-PSU_TRANG-TH-scaled-10.png\",\"width\":1769,\"height\":540,\"caption\":\"Prince of Songkla University, Trang Campus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/psutrangcampus5\",\"https:\\\/\\\/x.com\\\/psutrangcampus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/#\\\/schema\\\/person\\\/0482e4f1fb579d3e7720f8b7b22c8852\",\"name\":\"pronchita.s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a1d8b3c1cd26adb583941a5b94810826b8ac9f700641ab738ed7966cce6e959?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a1d8b3c1cd26adb583941a5b94810826b8ac9f700641ab738ed7966cce6e959?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a1d8b3c1cd26adb583941a5b94810826b8ac9f700641ab738ed7966cce6e959?s=96&d=mm&r=g\",\"caption\":\"pronchita.s\"},\"url\":\"https:\\\/\\\/www.psu.ac.th\\\/trang\\\/archives\\\/author\\\/pronchita-s\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e2d\u0e31\u0e15\u0e23\u0e32 - Prince of Songkla University, Trang Campus PSU Trang - \u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07","description":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 (PSU Trang) \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e43\u0e19\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.psu.ac.th\/trang\/archives\/33814","og_locale":"en_US","og_type":"article","og_title":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e2d\u0e31\u0e15\u0e23\u0e32 - Prince of Songkla University, Trang Campus PSU Trang - \u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07","og_description":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 (PSU Trang) \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e43\u0e19\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22","og_url":"https:\/\/www.psu.ac.th\/trang\/archives\/33814","og_site_name":"Prince of Songkla University, Trang Campus","article_publisher":"https:\/\/www.facebook.com\/psutrangcampus5","article_published_time":"2025-10-31T09:54:04+00:00","article_modified_time":"2025-11-03T01:37:42+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.jpg","type":"image\/jpeg"}],"author":"pronchita.s","twitter_card":"summary_large_image","twitter_creator":"@psutrangcampus","twitter_site":"@psutrangcampus","twitter_misc":{"Written by":"pronchita.s","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.psu.ac.th\/trang\/archives\/33814#article","isPartOf":{"@id":"https:\/\/www.psu.ac.th\/trang\/archives\/33814"},"author":{"name":"pronchita.s","@id":"https:\/\/www.psu.ac.th\/trang\/#\/schema\/person\/0482e4f1fb579d3e7720f8b7b22c8852"},"headline":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e2d\u0e31\u0e15\u0e23\u0e32","datePublished":"2025-10-31T09:54:04+00:00","dateModified":"2025-11-03T01:37:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.psu.ac.th\/trang\/archives\/33814"},"wordCount":6,"publisher":{"@id":"https:\/\/www.psu.ac.th\/trang\/#organization"},"image":{"@id":"https:\/\/www.psu.ac.th\/trang\/archives\/33814#primaryimage"},"thumbnailUrl":"https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.jpg","articleSection":["\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c","\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19","\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e30\u0e19\u0e33"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.psu.ac.th\/trang\/archives\/33814","url":"https:\/\/www.psu.ac.th\/trang\/archives\/33814","name":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e2d\u0e31\u0e15\u0e23\u0e32 - Prince of Songkla University, Trang Campus PSU Trang - \u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07","isPartOf":{"@id":"https:\/\/www.psu.ac.th\/trang\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.psu.ac.th\/trang\/archives\/33814#primaryimage"},"image":{"@id":"https:\/\/www.psu.ac.th\/trang\/archives\/33814#primaryimage"},"thumbnailUrl":"https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.jpg","datePublished":"2025-10-31T09:54:04+00:00","dateModified":"2025-11-03T01:37:42+00:00","description":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 (PSU Trang) \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e43\u0e19\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22","breadcrumb":{"@id":"https:\/\/www.psu.ac.th\/trang\/archives\/33814#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.psu.ac.th\/trang\/archives\/33814"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.psu.ac.th\/trang\/archives\/33814#primaryimage","url":"https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.jpg","contentUrl":"https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.jpg","width":940,"height":788},{"@type":"BreadcrumbList","@id":"https:\/\/www.psu.ac.th\/trang\/archives\/33814#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.psu.ac.th\/trang\/"},{"@type":"ListItem","position":2,"name":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e2d\u0e31\u0e15\u0e23\u0e32"}]},{"@type":"WebSite","@id":"https:\/\/www.psu.ac.th\/trang\/#website","url":"https:\/\/www.psu.ac.th\/trang\/","name":"Prince of Songkla University, Trang Campus","description":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e25\u0e27\u0e31\u0e15 \u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e21\u0e38\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33 1 \u0e43\u0e19 5 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e17\u0e38\u0e01\u0e14\u0e49\u0e32\u0e19 \u0e2a\u0e21\u0e31\u0e04\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e41\u0e25\u0e49\u0e27\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49","publisher":{"@id":"https:\/\/www.psu.ac.th\/trang\/#organization"},"alternateName":"\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 - PSU Trang","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.psu.ac.th\/trang\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.psu.ac.th\/trang\/#organization","name":"Prince of Songkla University, Trang Campus","alternateName":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07","url":"https:\/\/www.psu.ac.th\/trang\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.psu.ac.th\/trang\/#\/schema\/logo\/image\/","url":"https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/2019\/12\/cropped-PSU_TRANG-TH-scaled-10.png","contentUrl":"https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/2019\/12\/cropped-PSU_TRANG-TH-scaled-10.png","width":1769,"height":540,"caption":"Prince of Songkla University, Trang Campus"},"image":{"@id":"https:\/\/www.psu.ac.th\/trang\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/psutrangcampus5","https:\/\/x.com\/psutrangcampus"]},{"@type":"Person","@id":"https:\/\/www.psu.ac.th\/trang\/#\/schema\/person\/0482e4f1fb579d3e7720f8b7b22c8852","name":"pronchita.s","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9a1d8b3c1cd26adb583941a5b94810826b8ac9f700641ab738ed7966cce6e959?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9a1d8b3c1cd26adb583941a5b94810826b8ac9f700641ab738ed7966cce6e959?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9a1d8b3c1cd26adb583941a5b94810826b8ac9f700641ab738ed7966cce6e959?s=96&d=mm&r=g","caption":"pronchita.s"},"url":"https:\/\/www.psu.ac.th\/trang\/archives\/author\/pronchita-s"}]}},"rttpg_featured_image_url":{"full":["https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.jpg",940,788,false],"landscape":["https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.jpg",940,788,false],"portraits":["https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.jpg",940,788,false],"thumbnail":["https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04-300x251.jpg",300,251,true],"medium":["https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04-500x419.jpg",500,419,true],"large":["https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.jpg",940,788,false],"thumblist":["https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04-300x300.jpg",300,300,true],"meccarouselthumb":["https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04-474x324.jpg",474,324,true],"gridsquare":["https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04-391x260.jpg",391,260,true],"tileview":["https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04-300x400.jpg",300,400,true],"1536x1536":["https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.jpg",940,788,false],"2048x2048":["https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04.jpg",940,788,false],"ocean-thumb-m":["https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04-600x600.jpg",600,600,true],"ocean-thumb-ml":["https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04-800x450.jpg",800,450,true],"ocean-thumb-l":["https:\/\/www.psu.ac.th\/trang\/wp-content\/uploads\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04-940x700.jpg",940,700,true]},"rttpg_author":{"display_name":"pronchita.s","author_link":"https:\/\/www.psu.ac.th\/trang\/archives\/author\/pronchita-s"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/www.psu.ac.th\/trang\/archives\/category\/newsth\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b2%e0%b8%aa%e0%b8%b1%e0%b8%a1%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-th\" rel=\"category tag\">\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/a> <a href=\"https:\/\/www.psu.ac.th\/trang\/archives\/category\/newsth\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%aa%e0%b8%a1%e0%b8%b1%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%b2%e0%b8%99\" rel=\"category tag\">\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19<\/a> <a href=\"https:\/\/www.psu.ac.th\/trang\/archives\/category\/newsth\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b9%81%e0%b8%99%e0%b8%b0%e0%b8%99%e0%b8%b3\" rel=\"category tag\">\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e30\u0e19\u0e33<\/a>","rttpg_excerpt":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e2d\u0e31\u0e15\u0e23\u0e32\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e1a\u0e31\u0e14\u0e19\u0e35\u0e49 \u0e08\u0e19\u0e16\u0e36\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 28 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2568\u00a0 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e17\u0e32\u0e07\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u00a0 https:\/\/resume.psu.ac.th \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e14\u0e31\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e41\u0e19\u0e1a\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e19\u0e35\u0e49","_links":{"self":[{"href":"https:\/\/www.psu.ac.th\/trang\/wp-json\/wp\/v2\/posts\/33814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psu.ac.th\/trang\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psu.ac.th\/trang\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psu.ac.th\/trang\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psu.ac.th\/trang\/wp-json\/wp\/v2\/comments?post=33814"}],"version-history":[{"count":1,"href":"https:\/\/www.psu.ac.th\/trang\/wp-json\/wp\/v2\/posts\/33814\/revisions"}],"predecessor-version":[{"id":33816,"href":"https:\/\/www.psu.ac.th\/trang\/wp-json\/wp\/v2\/posts\/33814\/revisions\/33816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psu.ac.th\/trang\/wp-json\/wp\/v2\/media\/33819"}],"wp:attachment":[{"href":"https:\/\/www.psu.ac.th\/trang\/wp-json\/wp\/v2\/media?parent=33814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psu.ac.th\/trang\/wp-json\/wp\/v2\/categories?post=33814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psu.ac.th\/trang\/wp-json\/wp\/v2\/tags?post=33814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}