{"id":65064,"date":"2023-04-10T09:48:30","date_gmt":"2023-04-10T02:48:30","guid":{"rendered":"https:\/\/www.phuket.psu.ac.th\/?p=65064"},"modified":"2023-04-10T13:32:51","modified_gmt":"2023-04-10T06:32:51","slug":"%e0%b8%a1-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%81%e0%b9%87%e0%b8%95-%e0%b8%a3%e0%b9%88%e0%b8%a7%e0%b8%a1%e0%b8%a7%e0%b8%b2%e0%b8%87%e0%b8%9e%e0%b8%a7%e0%b8%87%e0%b8%a1%e0%b8%b2%e0%b8%a5","status":"publish","type":"post","link":"https:\/\/www.psu.ac.th\/phuket\/65064\/","title":{"rendered":"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35  (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"65064\" class=\"elementor elementor-65064 elementor-bc-flex-widget\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-1a51e923 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"61564\" data-id=\"1a51e923\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ed09075\" data-eae-slider=\"8271\" data-id=\"2ed09075\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5605fbce elementor-widget elementor-widget-heading\" data-id=\"5605fbce\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 \n<br>(\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5020b5d9 elementor-widget elementor-widget-text-editor\" data-id=\"5020b5d9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e19\u0e33\u0e42\u0e14\u0e22\u0e14\u0e23.\u0e09\u0e01\u0e32\u0e08\u0e01\u0e34\u0e08 \u0e41\u0e17\u0e48\u0e19\u0e0a\u0e31\u0e22\u0e01\u0e38\u0e25 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e2d\u0e2d\u0e01\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e19\u0e04\u0e23\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e43\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e13 \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2d\u0e19\u0e38\u0e2a\u0e32\u0e27\u0e23\u0e35\u0e22\u0e4c\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e40\u0e02\u0e32\u0e23\u0e31\u0e07 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2566<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e14\u0e31\u0e07\u0e04\u0e33\u0e01\u0e25\u0e48\u0e32\u0e27\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e27\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\u0e43\u0e2b\u0e49\u0e17\u0e48\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19 \u201c\u0e14\u0e27\u0e07\u0e1b\u0e23\u0e30\u0e17\u0e35\u0e1b\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e22\u0e1d\u0e31\u0e48\u0e07\u0e17\u0e30\u0e40\u0e25\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01\u201d \u0e2b\u0e23\u0e37\u0e2d \u201c\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e08\u0e34\u0e15\u0e43\u0e08\u0e07\u0e14\u0e07\u0e32\u0e21\u201d \u201c\u0e22\u0e2d\u0e14\u0e19\u0e31\u0e01\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e43\u0e19\u0e23\u0e2d\u0e1a 200 \u0e1b\u0e35 \u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e22\u0e1d\u0e31\u0e48\u0e07\u0e17\u0e30\u0e40\u0e25\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01\u201d \u0e2d\u0e19\u0e38\u0e2a\u0e32\u0e27\u0e23\u0e35\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e08\u0e30\u0e23\u0e33\u0e25\u0e36\u0e01\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e17\u0e48\u0e32\u0e19\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e40\u0e0a\u0e48\u0e19 \u0e28\u0e32\u0e25\u0e32\u0e01\u0e25\u0e32\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e18\u0e19\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e32\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e15\u0e33\u0e23\u0e27\u0e08 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e27\u0e0a\u0e34\u0e23\u0e30\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e16\u0e19\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19<\/div>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-5575465 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"32305\" data-id=\"5575465\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ae215ed\" data-eae-slider=\"29674\" data-id=\"ae215ed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9cd6a2a elementor-widget elementor-widget-image\" data-id=\"9cd6a2a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2023\/04\/65064_1-1024x768.jpg\" class=\"attachment-large size-large wp-image-65084\" alt=\"\" srcset=\"https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2023\/04\/65064_1-1024x768.jpg 1024w, https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2023\/04\/65064_1-300x225.jpg 300w, https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2023\/04\/65064_1-768x576.jpg 768w, https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2023\/04\/65064_1-350x262.jpg 350w, https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2023\/04\/65064_1.jpg 1479w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e19\u0e33\u0e42\u0e14\u0e22\u0e14\u0e23.\u0e09\u0e01\u0e32\u0e08\u0e01\u0e34\u0e08 \u0e41\u0e17\u0e48\u0e19\u0e0a\u0e31\u0e22\u0e01\u0e38\u0e25 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e2d\u0e2d\u0e01\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e19\u0e04\u0e23\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e43\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e13 \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2d\u0e19\u0e38\u0e2a\u0e32\u0e27\u0e23\u0e35\u0e22\u0e4c\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e40\u0e02\u0e32\u0e23\u0e31\u0e07 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2566 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e14\u0e31\u0e07\u0e04\u0e33\u0e01\u0e25\u0e48\u0e32\u0e27\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e27\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\u0e43\u0e2b\u0e49\u0e17\u0e48\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19 \u201c\u0e14\u0e27\u0e07\u0e1b\u0e23\u0e30\u0e17\u0e35\u0e1b\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e22\u0e1d\u0e31\u0e48\u0e07\u0e17\u0e30\u0e40\u0e25\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01\u201d \u0e2b\u0e23\u0e37\u0e2d \u201c\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e08\u0e34\u0e15\u0e43\u0e08\u0e07\u0e14\u0e07\u0e32\u0e21\u201d \u201c\u0e22\u0e2d\u0e14\u0e19\u0e31\u0e01\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e43\u0e19\u0e23\u0e2d\u0e1a 200 \u0e1b\u0e35 \u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e22\u0e1d\u0e31\u0e48\u0e07\u0e17\u0e30\u0e40\u0e25\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01\u201d \u0e2d\u0e19\u0e38\u0e2a\u0e32\u0e27\u0e23\u0e35\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e08\u0e30\u0e23\u0e33\u0e25\u0e36\u0e01\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e17\u0e48\u0e32\u0e19\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e40\u0e0a\u0e48\u0e19 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":65157,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[]},"categories":[65,318],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.psu.ac.th\/phuket\/65064\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus\" \/>\n<meta property=\"og:description\" content=\"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e19\u0e33\u0e42\u0e14\u0e22\u0e14\u0e23.\u0e09\u0e01\u0e32\u0e08\u0e01\u0e34\u0e08 \u0e41\u0e17\u0e48\u0e19\u0e0a\u0e31\u0e22\u0e01\u0e38\u0e25 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e2d\u0e2d\u0e01\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e19\u0e04\u0e23\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e43\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e13 \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2d\u0e19\u0e38\u0e2a\u0e32\u0e27\u0e23\u0e35\u0e22\u0e4c\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e40\u0e02\u0e32\u0e23\u0e31\u0e07 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2566 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e14\u0e31\u0e07\u0e04\u0e33\u0e01\u0e25\u0e48\u0e32\u0e27\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e27\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\u0e43\u0e2b\u0e49\u0e17\u0e48\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19 \u201c\u0e14\u0e27\u0e07\u0e1b\u0e23\u0e30\u0e17\u0e35\u0e1b\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e22\u0e1d\u0e31\u0e48\u0e07\u0e17\u0e30\u0e40\u0e25\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01\u201d \u0e2b\u0e23\u0e37\u0e2d \u201c\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e08\u0e34\u0e15\u0e43\u0e08\u0e07\u0e14\u0e07\u0e32\u0e21\u201d \u201c\u0e22\u0e2d\u0e14\u0e19\u0e31\u0e01\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e43\u0e19\u0e23\u0e2d\u0e1a 200 \u0e1b\u0e35 \u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e22\u0e1d\u0e31\u0e48\u0e07\u0e17\u0e30\u0e40\u0e25\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01\u201d \u0e2d\u0e19\u0e38\u0e2a\u0e32\u0e27\u0e23\u0e35\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e08\u0e30\u0e23\u0e33\u0e25\u0e36\u0e01\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e17\u0e48\u0e32\u0e19\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e40\u0e0a\u0e48\u0e19 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.psu.ac.th\/phuket\/65064\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/phuketcampus\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-10T02:48:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-10T06:32:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2023\/04\/65064.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Warisa Samathi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Warisa Samathi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/65064\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/65064\/\"},\"author\":{\"name\":\"Warisa Samathi\",\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/#\/schema\/person\/238eab51ba00d9f810b126ac715235f8\"},\"headline\":\"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"datePublished\":\"2023-04-10T02:48:30+00:00\",\"dateModified\":\"2023-04-10T06:32:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/65064\/\"},\"wordCount\":8,\"publisher\":{\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/#organization\"},\"articleSection\":[\"News_Staff_TH\",\"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/65064\/\",\"url\":\"https:\/\/www.psu.ac.th\/phuket\/65064\/\",\"name\":\"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus\",\"isPartOf\":{\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/#website\"},\"datePublished\":\"2023-04-10T02:48:30+00:00\",\"dateModified\":\"2023-04-10T06:32:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/65064\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.psu.ac.th\/phuket\/65064\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/65064\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.psu.ac.th\/phuket\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/#website\",\"url\":\"https:\/\/www.psu.ac.th\/phuket\/\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus\",\"description\":\"\u0e21.\u0e2d. \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, \u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e14\u0e49 \u0e40\u0e25\u0e48\u0e19\u0e44\u0e14\u0e49 \u2013 \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e04\u0e37\u0e2d \u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e48!, University in phuket\",\"publisher\":{\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.psu.ac.th\/phuket\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/#organization\",\"name\":\"Prince of Songkla University, Phuket Campus\",\"url\":\"https:\/\/www.psu.ac.th\/phuket\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2019\/03\/cropped-PSU_PHUKET-EN.png\",\"contentUrl\":\"https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2019\/03\/cropped-PSU_PHUKET-EN.png\",\"width\":1895,\"height\":712,\"caption\":\"Prince of Songkla University, Phuket Campus\"},\"image\":{\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/phuketcampus\",\"https:\/\/www.youtube.com\/@psuphuketchannel4746\",\"https:\/\/www.tiktok.com\/@psu_phuket\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/#\/schema\/person\/238eab51ba00d9f810b126ac715235f8\",\"name\":\"Warisa Samathi\",\"url\":\"https:\/\/www.psu.ac.th\/phuket\/author\/warisa-s\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.psu.ac.th\/phuket\/65064\/","og_locale":"en_US","og_type":"article","og_title":"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus","og_description":"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e19\u0e33\u0e42\u0e14\u0e22\u0e14\u0e23.\u0e09\u0e01\u0e32\u0e08\u0e01\u0e34\u0e08 \u0e41\u0e17\u0e48\u0e19\u0e0a\u0e31\u0e22\u0e01\u0e38\u0e25 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e2d\u0e2d\u0e01\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e19\u0e04\u0e23\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e43\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e13 \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2d\u0e19\u0e38\u0e2a\u0e32\u0e27\u0e23\u0e35\u0e22\u0e4c\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e40\u0e02\u0e32\u0e23\u0e31\u0e07 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2566 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e14\u0e31\u0e07\u0e04\u0e33\u0e01\u0e25\u0e48\u0e32\u0e27\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e27\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\u0e43\u0e2b\u0e49\u0e17\u0e48\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19 \u201c\u0e14\u0e27\u0e07\u0e1b\u0e23\u0e30\u0e17\u0e35\u0e1b\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e22\u0e1d\u0e31\u0e48\u0e07\u0e17\u0e30\u0e40\u0e25\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01\u201d \u0e2b\u0e23\u0e37\u0e2d \u201c\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e08\u0e34\u0e15\u0e43\u0e08\u0e07\u0e14\u0e07\u0e32\u0e21\u201d \u201c\u0e22\u0e2d\u0e14\u0e19\u0e31\u0e01\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e43\u0e19\u0e23\u0e2d\u0e1a 200 \u0e1b\u0e35 \u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e22\u0e1d\u0e31\u0e48\u0e07\u0e17\u0e30\u0e40\u0e25\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01\u201d \u0e2d\u0e19\u0e38\u0e2a\u0e32\u0e27\u0e23\u0e35\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e08\u0e30\u0e23\u0e33\u0e25\u0e36\u0e01\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e17\u0e48\u0e32\u0e19\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e40\u0e0a\u0e48\u0e19 [&hellip;]","og_url":"https:\/\/www.psu.ac.th\/phuket\/65064\/","og_site_name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus","article_publisher":"https:\/\/www.facebook.com\/phuketcampus","article_published_time":"2023-04-10T02:48:30+00:00","article_modified_time":"2023-04-10T06:32:51+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2023\/04\/65064.png","type":"image\/png"}],"author":"Warisa Samathi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Warisa Samathi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.psu.ac.th\/phuket\/65064\/#article","isPartOf":{"@id":"https:\/\/www.psu.ac.th\/phuket\/65064\/"},"author":{"name":"Warisa Samathi","@id":"https:\/\/www.psu.ac.th\/phuket\/#\/schema\/person\/238eab51ba00d9f810b126ac715235f8"},"headline":"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15","datePublished":"2023-04-10T02:48:30+00:00","dateModified":"2023-04-10T06:32:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.psu.ac.th\/phuket\/65064\/"},"wordCount":8,"publisher":{"@id":"https:\/\/www.psu.ac.th\/phuket\/#organization"},"articleSection":["News_Staff_TH","\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.psu.ac.th\/phuket\/65064\/","url":"https:\/\/www.psu.ac.th\/phuket\/65064\/","name":"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus","isPartOf":{"@id":"https:\/\/www.psu.ac.th\/phuket\/#website"},"datePublished":"2023-04-10T02:48:30+00:00","dateModified":"2023-04-10T06:32:51+00:00","breadcrumb":{"@id":"https:\/\/www.psu.ac.th\/phuket\/65064\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.psu.ac.th\/phuket\/65064\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.psu.ac.th\/phuket\/65064\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.psu.ac.th\/phuket\/"},{"@type":"ListItem","position":2,"name":"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e23\u0e31\u0e29\u0e0e\u0e32\u0e19\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e21\u0e2b\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e04\u0e2d\u0e0b\u0e34\u0e21\u0e1a\u0e35\u0e49 \u0e13 \u0e23\u0e30\u0e19\u0e2d\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15"}]},{"@type":"WebSite","@id":"https:\/\/www.psu.ac.th\/phuket\/#website","url":"https:\/\/www.psu.ac.th\/phuket\/","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus","description":"\u0e21.\u0e2d. \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, \u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e14\u0e49 \u0e40\u0e25\u0e48\u0e19\u0e44\u0e14\u0e49 \u2013 \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e04\u0e37\u0e2d \u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e48!, University in phuket","publisher":{"@id":"https:\/\/www.psu.ac.th\/phuket\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.psu.ac.th\/phuket\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.psu.ac.th\/phuket\/#organization","name":"Prince of Songkla University, Phuket Campus","url":"https:\/\/www.psu.ac.th\/phuket\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.psu.ac.th\/phuket\/#\/schema\/logo\/image\/","url":"https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2019\/03\/cropped-PSU_PHUKET-EN.png","contentUrl":"https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2019\/03\/cropped-PSU_PHUKET-EN.png","width":1895,"height":712,"caption":"Prince of Songkla University, Phuket Campus"},"image":{"@id":"https:\/\/www.psu.ac.th\/phuket\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/phuketcampus","https:\/\/www.youtube.com\/@psuphuketchannel4746","https:\/\/www.tiktok.com\/@psu_phuket"]},{"@type":"Person","@id":"https:\/\/www.psu.ac.th\/phuket\/#\/schema\/person\/238eab51ba00d9f810b126ac715235f8","name":"Warisa Samathi","url":"https:\/\/www.psu.ac.th\/phuket\/author\/warisa-s\/"}]}},"_links":{"self":[{"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/posts\/65064"}],"collection":[{"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/comments?post=65064"}],"version-history":[{"count":3,"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/posts\/65064\/revisions"}],"predecessor-version":[{"id":65190,"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/posts\/65064\/revisions\/65190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/media\/65157"}],"wp:attachment":[{"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/media?parent=65064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/categories?post=65064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/tags?post=65064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}