{"id":19463,"date":"2020-10-08T15:20:04","date_gmt":"2020-10-08T08:20:04","guid":{"rendered":"https:\/\/www.phuket.psu.ac.th\/?p=19463"},"modified":"2020-10-09T16:08:04","modified_gmt":"2020-10-09T09:08:04","slug":"%e0%b8%a1-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%81%e0%b9%87%e0%b8%95-%e0%b8%a3%e0%b9%88%e0%b8%a7%e0%b8%a1%e0%b9%81%e0%b8%a5%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%a5%e0%b8%b5%e0%b9%88%e0%b8%a2","status":"publish","type":"post","link":"https:\/\/www.psu.ac.th\/phuket\/19463\/","title":{"rendered":"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 UI Green Metrix World University Ranking 2020"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"19463\" class=\"elementor elementor-19463 elementor-bc-flex-widget\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-4b403c8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"1117\" data-id=\"4b403c8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31d5b6e\" data-eae-slider=\"72240\" data-id=\"31d5b6e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11166dc elementor-widget elementor-widget-heading\" data-id=\"11166dc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 UI Green Metrix World University Ranking 2020<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-8b98ee4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"35455\" data-id=\"8b98ee4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3e50735\" data-eae-slider=\"55966\" data-id=\"3e50735\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea914af elementor-widget elementor-widget-text-editor\" data-id=\"ea914af\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<hr \/><p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e19\u0e33\u0e42\u0e14\u0e22\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e2d\u0e32\u0e04\u0e21 \u0e27\u0e31\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e01\u0e23\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19 UI Green Metrix World University Ranking 2020 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e23\u0e34\u0e07<br \/>\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (SUN Thailand) \u0e08\u0e30\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (SUN Thailand) \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 3\/2563 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 8-10 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2563 \u0e13 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e40\u0e1e\u0e34\u0e23\u0e4c\u0e25 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e34\u0e15\u0e23\u0e15\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e43\u0e19\u0e21\u0e34\u0e15\u0e34\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01 34 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19<br \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e17\u0e35\u0e21\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22(SUN Thailand) \u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19 UI Green Metrix World University Ranking 2020 \u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e31\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e02\u0e2d\u0e07 5 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e42\u0e14\u0e22 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23. \u0e2a\u0e21\u0e1e\u0e23 \u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e4c \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e48\u0e2d\u0e41\u0e23\u0e48 \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e19\u0e27\u0e32 \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e21\u0e48\u0e32\u0e2b\u0e19\u0e34\u0e01 \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-28add60 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"330\" data-id=\"28add60\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e7b815c\" data-eae-slider=\"49817\" data-id=\"e7b815c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-859b869 elementor-skin-slideshow elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"859b869\" data-element_type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;slideshow&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-main-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"120923154_10159445650758115_5296725834196143471_n (1)\" style=\"background-image: url(&#039;https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2020\/10\/120923154_10159445650758115_5296725834196143471_n-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"120968495_10159445650683115_4545370941604729123_n\" style=\"background-image: url(&#039;https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2020\/10\/120968495_10159445650683115_4545370941604729123_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"120955163_10159445650533115_8221179973861267201_n\" style=\"background-image: url(&#039;https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2020\/10\/120955163_10159445650533115_8221179973861267201_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"120900852_10159445650883115_2499876408129814249_n\" style=\"background-image: url(&#039;https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2020\/10\/120900852_10159445650883115_2499876408129814249_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"121060568_10159445650593115_2362746746509132146_n\" style=\"background-image: url(&#039;https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2020\/10\/121060568_10159445650593115_2362746746509132146_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-thumbnails-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"120923154_10159445650758115_5296725834196143471_n (1)\" style=\"background-image: url(&#039;https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2020\/10\/120923154_10159445650758115_5296725834196143471_n-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"120968495_10159445650683115_4545370941604729123_n\" style=\"background-image: url(&#039;https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2020\/10\/120968495_10159445650683115_4545370941604729123_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"120955163_10159445650533115_8221179973861267201_n\" style=\"background-image: url(&#039;https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2020\/10\/120955163_10159445650533115_8221179973861267201_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"120900852_10159445650883115_2499876408129814249_n\" style=\"background-image: url(&#039;https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2020\/10\/120900852_10159445650883115_2499876408129814249_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"121060568_10159445650593115_2362746746509132146_n\" style=\"background-image: url(&#039;https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2020\/10\/121060568_10159445650593115_2362746746509132146_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-313684e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"73961\" data-id=\"313684e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ab692ce\" data-eae-slider=\"46990\" data-id=\"ab692ce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 UI Green Metrix World University Ranking 2020 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e19\u0e33\u0e42\u0e14\u0e22\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e2d\u0e32\u0e04\u0e21 \u0e27\u0e31\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e01\u0e23\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19 UI Green Metrix World University Ranking 2020 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e23\u0e34\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (SUN Thailand) \u0e08\u0e30\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (SUN Thailand) \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 3\/2563 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 8-10 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2563 \u0e13 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e40\u0e1e\u0e34\u0e23\u0e4c\u0e25 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e34\u0e15\u0e23\u0e15\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e43\u0e19\u0e21\u0e34\u0e15\u0e34\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01 34 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19 &nbsp; &nbsp; [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19472,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[]},"categories":[339,65,383],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 UI Green Metrix World University Ranking 2020 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.psu.ac.th\/phuket\/19463\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 UI Green Metrix World University Ranking 2020 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus\" \/>\n<meta property=\"og:description\" content=\"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 UI Green Metrix World University Ranking 2020 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e19\u0e33\u0e42\u0e14\u0e22\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e2d\u0e32\u0e04\u0e21 \u0e27\u0e31\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e01\u0e23\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19 UI Green Metrix World University Ranking 2020 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e23\u0e34\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (SUN Thailand) \u0e08\u0e30\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (SUN Thailand) \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 3\/2563 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 8-10 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2563 \u0e13 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e40\u0e1e\u0e34\u0e23\u0e4c\u0e25 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e34\u0e15\u0e23\u0e15\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e43\u0e19\u0e21\u0e34\u0e15\u0e34\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01 34 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19 &nbsp; &nbsp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.psu.ac.th\/phuket\/19463\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/phuketcampus\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-08T08:20:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-09T09:08:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2020\/10\/19463.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Warisa Samathi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Warisa Samathi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/19463\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/19463\/\"},\"author\":{\"name\":\"Warisa Samathi\",\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/#\/schema\/person\/238eab51ba00d9f810b126ac715235f8\"},\"headline\":\"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 UI Green Metrix World University Ranking 2020\",\"datePublished\":\"2020-10-08T08:20:04+00:00\",\"dateModified\":\"2020-10-09T09:08:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/19463\/\"},\"wordCount\":43,\"publisher\":{\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/#organization\"},\"articleSection\":[\"Highlights_Staff_TH\",\"News_Staff_TH\",\"PSU Phuket Today\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/19463\/\",\"url\":\"https:\/\/www.psu.ac.th\/phuket\/19463\/\",\"name\":\"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 UI Green Metrix World University Ranking 2020 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus\",\"isPartOf\":{\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/#website\"},\"datePublished\":\"2020-10-08T08:20:04+00:00\",\"dateModified\":\"2020-10-09T09:08:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/19463\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.psu.ac.th\/phuket\/19463\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/19463\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.psu.ac.th\/phuket\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 UI Green Metrix World University Ranking 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/#website\",\"url\":\"https:\/\/www.psu.ac.th\/phuket\/\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus\",\"description\":\"\u0e21.\u0e2d. \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, \u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e14\u0e49 \u0e40\u0e25\u0e48\u0e19\u0e44\u0e14\u0e49 \u2013 \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e04\u0e37\u0e2d \u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e48!, University in phuket\",\"publisher\":{\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.psu.ac.th\/phuket\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/#organization\",\"name\":\"Prince of Songkla University, Phuket Campus\",\"url\":\"https:\/\/www.psu.ac.th\/phuket\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2019\/03\/cropped-PSU_PHUKET-EN.png\",\"contentUrl\":\"https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2019\/03\/cropped-PSU_PHUKET-EN.png\",\"width\":1895,\"height\":712,\"caption\":\"Prince of Songkla University, Phuket Campus\"},\"image\":{\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/phuketcampus\",\"https:\/\/www.youtube.com\/@psuphuketchannel4746\",\"https:\/\/www.tiktok.com\/@psu_phuket\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.psu.ac.th\/phuket\/#\/schema\/person\/238eab51ba00d9f810b126ac715235f8\",\"name\":\"Warisa Samathi\",\"url\":\"https:\/\/www.psu.ac.th\/phuket\/author\/warisa-s\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 UI Green Metrix World University Ranking 2020 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.psu.ac.th\/phuket\/19463\/","og_locale":"en_US","og_type":"article","og_title":"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 UI Green Metrix World University Ranking 2020 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus","og_description":"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 UI Green Metrix World University Ranking 2020 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e19\u0e33\u0e42\u0e14\u0e22\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e2d\u0e32\u0e04\u0e21 \u0e27\u0e31\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e01\u0e23\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19 UI Green Metrix World University Ranking 2020 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e23\u0e34\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (SUN Thailand) \u0e08\u0e30\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (SUN Thailand) \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 3\/2563 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 8-10 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2563 \u0e13 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e40\u0e1e\u0e34\u0e23\u0e4c\u0e25 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e34\u0e15\u0e23\u0e15\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e43\u0e19\u0e21\u0e34\u0e15\u0e34\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01 34 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19 &nbsp; &nbsp; [&hellip;]","og_url":"https:\/\/www.psu.ac.th\/phuket\/19463\/","og_site_name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus","article_publisher":"https:\/\/www.facebook.com\/phuketcampus","article_published_time":"2020-10-08T08:20:04+00:00","article_modified_time":"2020-10-09T09:08:04+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2020\/10\/19463.jpg","type":"image\/jpeg"}],"author":"Warisa Samathi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Warisa Samathi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.psu.ac.th\/phuket\/19463\/#article","isPartOf":{"@id":"https:\/\/www.psu.ac.th\/phuket\/19463\/"},"author":{"name":"Warisa Samathi","@id":"https:\/\/www.psu.ac.th\/phuket\/#\/schema\/person\/238eab51ba00d9f810b126ac715235f8"},"headline":"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 UI Green Metrix World University Ranking 2020","datePublished":"2020-10-08T08:20:04+00:00","dateModified":"2020-10-09T09:08:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.psu.ac.th\/phuket\/19463\/"},"wordCount":43,"publisher":{"@id":"https:\/\/www.psu.ac.th\/phuket\/#organization"},"articleSection":["Highlights_Staff_TH","News_Staff_TH","PSU Phuket Today"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.psu.ac.th\/phuket\/19463\/","url":"https:\/\/www.psu.ac.th\/phuket\/19463\/","name":"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 UI Green Metrix World University Ranking 2020 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus","isPartOf":{"@id":"https:\/\/www.psu.ac.th\/phuket\/#website"},"datePublished":"2020-10-08T08:20:04+00:00","dateModified":"2020-10-09T09:08:04+00:00","breadcrumb":{"@id":"https:\/\/www.psu.ac.th\/phuket\/19463\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.psu.ac.th\/phuket\/19463\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.psu.ac.th\/phuket\/19463\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.psu.ac.th\/phuket\/"},{"@type":"ListItem","position":2,"name":"\u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 UI Green Metrix World University Ranking 2020"}]},{"@type":"WebSite","@id":"https:\/\/www.psu.ac.th\/phuket\/#website","url":"https:\/\/www.psu.ac.th\/phuket\/","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, Prince of Songkla University, Phuket Campus","description":"\u0e21.\u0e2d. \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15, \u0e21.\u0e2d.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e14\u0e49 \u0e40\u0e25\u0e48\u0e19\u0e44\u0e14\u0e49 \u2013 \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e04\u0e37\u0e2d \u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e48!, University in phuket","publisher":{"@id":"https:\/\/www.psu.ac.th\/phuket\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.psu.ac.th\/phuket\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.psu.ac.th\/phuket\/#organization","name":"Prince of Songkla University, Phuket Campus","url":"https:\/\/www.psu.ac.th\/phuket\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.psu.ac.th\/phuket\/#\/schema\/logo\/image\/","url":"https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2019\/03\/cropped-PSU_PHUKET-EN.png","contentUrl":"https:\/\/www.psu.ac.th\/phuket\/wp-content\/uploads\/2019\/03\/cropped-PSU_PHUKET-EN.png","width":1895,"height":712,"caption":"Prince of Songkla University, Phuket Campus"},"image":{"@id":"https:\/\/www.psu.ac.th\/phuket\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/phuketcampus","https:\/\/www.youtube.com\/@psuphuketchannel4746","https:\/\/www.tiktok.com\/@psu_phuket"]},{"@type":"Person","@id":"https:\/\/www.psu.ac.th\/phuket\/#\/schema\/person\/238eab51ba00d9f810b126ac715235f8","name":"Warisa Samathi","url":"https:\/\/www.psu.ac.th\/phuket\/author\/warisa-s\/"}]}},"_links":{"self":[{"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/posts\/19463"}],"collection":[{"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/comments?post=19463"}],"version-history":[{"count":4,"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/posts\/19463\/revisions"}],"predecessor-version":[{"id":19473,"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/posts\/19463\/revisions\/19473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/media\/19472"}],"wp:attachment":[{"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/media?parent=19463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/categories?post=19463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psu.ac.th\/phuket\/wp-json\/wp\/v2\/tags?post=19463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}